{"id":339,"date":"2024-06-18T16:05:21","date_gmt":"2024-06-18T14:05:21","guid":{"rendered":"https:\/\/temporaneo.arciserviziocivile.it\/ravenna\/?p=339"},"modified":"2024-06-18T16:09:20","modified_gmt":"2024-06-18T14:09:20","slug":"bando-servizio-civile-regionale-2024","status":"publish","type":"post","link":"https:\/\/temporaneo.arciserviziocivile.it\/ravenna\/2024\/06\/18\/bando-servizio-civile-regionale-2024\/","title":{"rendered":"Bando Servizio Civile Regionale 2024"},"content":{"rendered":"\n<p>La Regione Emilia-Romagna ha pubblicato il bando di Servizio Civile Regionale 2024; il termine per la presentazione della candidatura \u00e8 fissato per <strong>luned\u00ec 15 luglio alle ore 14:00.<\/strong><\/p>\n\n\n\n<p>Il <strong>Servizio Civile Regionale<\/strong> \u00e8 l\u2019opportunit\u00e0 che la Regione Emilia-Romagna offre all\u0437 giovani dai 18 ai 30 anni non compiuti di investire alcuni mesi della propria vita in azioni legate al territorio e alla comunit\u00e0. \u00c8 finalizzato alla promozione della pace, della giusti\u00adzia sociale e della cittadinanza attiva e alla difesa non armata e nonviolenta attraverso la partecipazione a progetti di assistenza, protezione civile, valorizzazione del patrimonio storico, artistico e culturale, educazione e promozione culturale e sociale, riqualificazione urbana, agricoltura sociale, promozione della pace tra i popoli e della nonviolenza.<\/p>\n\n\n\n<p>Il testo integrale del bando con tutti i dettagli \u00e8 disponibile al sito<a href=\"https:\/\/sociale.regione.emilia-romagna.it\/servizio-civile\/avvisi\/dol-er-documenti-avvisi\/pubblicati-gli-avvisi-del-servizio-civile-regionale\"> https:\/\/sociale.regione.emilia-romagna.it\/servizio-civile\/avvisi\/dol-er-documenti-avvisi\/pubblicati-gli-avvisi-del-servizio-civile-regionale<\/a>&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>Tra i progetti a bando diversi quelli che riguardano organizzazioni socie e partner di Arci Servizio Civile APS.<\/p>\n\n\n\n<p><strong>Buone pratiche di cittadinanza<\/strong><\/p>\n\n\n\n<p>Settore\/area: Educazione e promozione culturale \/ Educazione e promozione ambientale<\/p>\n\n\n\n<p>Sede di attuazione: Cinoservizio Lugo (RA) \u2013 2 posti di cui 1 riservato a persone residenti o domiciliate in aree interne o montane<\/p>\n\n\n\n<p>Durata progetto: 8 mesi<\/p>\n\n\n\n<p>Data di avvio: 01\/10\/2024<\/p>\n\n\n\n<p><strong>Biblioteche e luoghi della cultura \u2013 SCR 2024<\/strong><\/p>\n\n\n\n<p>Settore\/area: Patrimonio storico, artistico e culturale \/ Cura e conservazione biblioteche, valorizzazione storie e culture locali<\/p>\n\n\n\n<p>Sedi di attuazione:<\/p>\n\n\n\n<ul>\n<li>Servizio scuola e cultura di Castellarano (RE) \u2013 2 posti di cui 1 riservato a giovani con disagio economico sociale<\/li>\n\n\n\n<li>Biblioteca di Montecchio Emilia (RE) \u2013 2 posti<\/li>\n\n\n\n<li>Comune di Reggiolo\/Biblioteca G. Ambrosoli (RE) \u2013 2 posti di cui 1 riservato a giovani con disagio economico sociale<\/li>\n<\/ul>\n\n\n\n<ul>\n<li>Multiplo\/Centro cultura Cavriago (RE) \u2013 2 posti di cui 1 riservato a giovani con disagio economico sociale<\/li>\n\n\n\n<li>Istituto Alcide Cervi di Gattatico (RE) \u2013 2 posti<\/li>\n\n\n\n<li>Fondazione di Cavriago (RE) \u2013 2 posti<\/li>\n\n\n\n<li>Biblioteca comunale Sognalibro di Casalgrande (RE) \u2013 2 posti di cui 1 riservato a giovani con disagio economico sociale<\/li>\n\n\n\n<li>MABIC di Maranello (MO) \u2013 2 posti<\/li>\n<\/ul>\n\n\n\n<p>Durata progetto: 11 mesi<\/p>\n\n\n\n<p>Data di avvio: 02\/09\/2024<\/p>\n\n\n\n<p><strong>Giovani in rete<\/strong><\/p>\n\n\n\n<p>Settore\/area: Educazione e promozione culturale \/ Educazione e promozione dei diritti del cittadino<\/p>\n\n\n\n<p>Sedi di attuazione:<\/p>\n\n\n\n<ul>\n<li>Centro interculturale movimenti di Cesena (FC) \u2013 1 posto<\/li>\n\n\n\n<li>Centro per gli Stranieri Sanzio Togni di Cesena (FC) \u2013 2 posti<\/li>\n<\/ul>\n\n\n\n<p>Durata progetto: 11 mesi<\/p>\n\n\n\n<p>Data di avvio: 02\/09\/2024<\/p>\n\n\n\n<p><strong>Congiunzioni culturali<\/strong><\/p>\n\n\n\n<p>Settore\/area: Educazione e promozione culturale \/ Educazione e promozione dei diritti del cittadino<\/p>\n\n\n\n<p>Sedi di attuazione:<\/p>\n\n\n\n<ul>\n<li>Biblioteca A. Baldini di Santarcangelo di Romagna (RN) \u2013 2 posti<\/li>\n\n\n\n<li>Comune di Poggio Torriana (RN) \u2013 1 posto<\/li>\n\n\n\n<li>Biblioteca comunale di Novafeltria (RN) \u2013 2 posti di cui 1 riservato a persone residenti o domiciliate in aree interne o montane<\/li>\n\n\n\n<li>Musei comunali di Rimini \u2013 2 posti<\/li>\n\n\n\n<li>Biblioteca Malatestiana di Cesena (FC) \u2013 2 posti<\/li>\n\n\n\n<li>Biblioteca comunale di Cesenatico (FC) \u2013 2 posti di cui 1 riservato a giovani con disagio economico sociale<\/li>\n<\/ul>\n\n\n\n<p>Durata progetto: 9 mesi<\/p>\n\n\n\n<p>Data di avvio: 01\/10\/2024<\/p>\n\n\n\n<p><strong>WildER &#8211; CRAS in prima linea<\/strong><strong><br><\/strong>Settore\/area: Agricoltura in zona di montagna, agricoltura sociale e biodiversit\u00e0 \/ Salvaguardia della biodiversit\u00e0<br>Sedi di attuazione:<\/p>\n\n\n\n<ul>\n<li>Centro Tutela e Ricerca Fauna Esotica e Selvatica di Monte Adone (BO) \u2013 4 posti di cui 1 riservato GMO<\/li>\n\n\n\n<li>CRAS Rimini \u2013 6 posti di cui 1 riservato GMO<\/li>\n<\/ul>\n\n\n\n<p>In entrambe le sedi 1 posto \u00e8 riservato a giovani non impegnati nello studio, n\u00e9 nel lavoro n\u00e9 nella formazione (Neet) o a giovani con bassa scolarizzazione per titolo di studio inferiore a quello di scuola secondaria di secondo grado o a giovani residenti o domiciliati nelle aree montane o interne.<\/p>\n\n\n\n<p>Durata progetto: 11 mesi<\/p>\n\n\n\n<p>Data di avvio: 02\/09\/2024<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Regione Emilia-Romagna ha pubblicato il bando di Servizio Civile Regionale 2024; il termine per la presentazione della candidatura \u00e8 fissato per luned\u00ec 15 luglio alle ore 14:00.<\/p>\n","protected":false},"author":1,"featured_media":340,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28,26,5,1],"tags":[],"_links":{"self":[{"href":"https:\/\/temporaneo.arciserviziocivile.it\/ravenna\/wp-json\/wp\/v2\/posts\/339"}],"collection":[{"href":"https:\/\/temporaneo.arciserviziocivile.it\/ravenna\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/temporaneo.arciserviziocivile.it\/ravenna\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/temporaneo.arciserviziocivile.it\/ravenna\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/temporaneo.arciserviziocivile.it\/ravenna\/wp-json\/wp\/v2\/comments?post=339"}],"version-history":[{"count":1,"href":"https:\/\/temporaneo.arciserviziocivile.it\/ravenna\/wp-json\/wp\/v2\/posts\/339\/revisions"}],"predecessor-version":[{"id":341,"href":"https:\/\/temporaneo.arciserviziocivile.it\/ravenna\/wp-json\/wp\/v2\/posts\/339\/revisions\/341"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/temporaneo.arciserviziocivile.it\/ravenna\/wp-json\/wp\/v2\/media\/340"}],"wp:attachment":[{"href":"https:\/\/temporaneo.arciserviziocivile.it\/ravenna\/wp-json\/wp\/v2\/media?parent=339"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/temporaneo.arciserviziocivile.it\/ravenna\/wp-json\/wp\/v2\/categories?post=339"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/temporaneo.arciserviziocivile.it\/ravenna\/wp-json\/wp\/v2\/tags?post=339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}