{"id":26,"date":"2016-03-14T15:05:17","date_gmt":"2016-03-14T14:05:17","guid":{"rendered":"http:\/\/temporaneo.arciserviziocivile.it\/ascnetwork\/rimini\/?page_id=23"},"modified":"2022-01-12T14:55:19","modified_gmt":"2022-01-12T13:55:19","slug":"servizio-civile","status":"publish","type":"page","link":"https:\/\/temporaneo.arciserviziocivile.it\/ravenna\/servizio-civile\/","title":{"rendered":"SERVIZIO CIVILE"},"content":{"rendered":"\n<p>Il\u00a0<span class=\"has-inline-color has-vivid-cyan-blue-color\">Servizio Civile Universale<\/span>\u00a0\u00e8 un anno di attivit\u00e0 e formazione costruito intorno al volontario.<\/p>\n\n\n\n<p>Il progetto rappresenta un&nbsp;percorso personale, di gruppo ed unico di promozione della pace, della cittadinanza attiva e della partecipazione. Ogni volontario, attraverso il proprio impegno pu\u00f2 riscoprire il significato dell\u2019essere cittadino e trasmetterlo agli altri.<\/p>\n\n\n\n<p>Il Servizio Civile Universale\u00a0\u00e8 la <span class=\"has-inline-color has-vivid-cyan-blue-color\">scelta volontaria<\/span> di dedicare alcuni mesi della propria vita al servizio di difesa, non armata e non violenta, della Patria, all\u2019educazione, alla pace tra i popoli e alla promozione dei valori fondativi della Repubblica italiana, attraverso azioni per le comunit\u00e0 e per il territorio.<\/p>\n\n\n\n<p>Il\u00a0Servizio Civile Universale\u00a0rappresenta una importante occasione di formazione e di crescita personale e professionale per\u00a0i<span class=\"has-inline-color has-vivid-cyan-blue-color\"> giovani tra i 18 e i 28 anni<\/span>, che sono un\u2019indispensabile e vitale risorsa per il progresso culturale, sociale ed economico del Paese.<\/p>\n\n\n\n<p>I\u00a0<span class=\"has-inline-color has-vivid-cyan-blue-color\">settori di intervento<\/span>\u00a0in Italia e all\u2019estero nei quali gli Enti propongono i progetti che vedono impegnati gli operatori volontari sono:<\/p>\n\n\n\n<ul><li>assistenza<\/li><li>protezione civile<\/li><li>patrimonio ambientale e riqualificazione urbana<\/li><li>patrimonio storico, artistico e culturale<\/li><li>educazione e promozione culturale, paesaggistica, ambientale, dello sport, del turismo sostenibile e sociale<\/li><li>agricoltura in zona di montagna, agricoltura sociale e biodiversit\u00e0<\/li><li>promozione della pace tra i popoli, della nonviolenza e della difesa non armata; promozione e tutela dei diritti umani; cooperazione allo sviluppo; promozione della cultura italiana all\u2019estero e sostegno alle comunit\u00e0 di italiani all\u2019estero.<\/li><\/ul>\n\n\n\n<p>Con il\u00a0Dlgs. 6 marzo 2017, n. 40, il servizio civile universale punta ad accogliere tutte le richieste di partecipazione da parte dei giovani che, per scelta volontaria, intendono fare un\u2019esperienza di grande valore formativo e civile, in grado anche di dare loro competenze utili per l\u2019immissione nel mondo del lavoro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il\u00a0Servizio Civile Universale\u00a0\u00e8 un anno di attivit\u00e0 e formazione costruito intorno al volontario. Il progetto rappresenta un&nbsp;percorso personale, di gruppo ed unico di promozione della pace, della cittadinanza attiva e&#8230;<\/p>\n","protected":false},"author":46,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"_links":{"self":[{"href":"https:\/\/temporaneo.arciserviziocivile.it\/ravenna\/wp-json\/wp\/v2\/pages\/26"}],"collection":[{"href":"https:\/\/temporaneo.arciserviziocivile.it\/ravenna\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/temporaneo.arciserviziocivile.it\/ravenna\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/temporaneo.arciserviziocivile.it\/ravenna\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/temporaneo.arciserviziocivile.it\/ravenna\/wp-json\/wp\/v2\/comments?post=26"}],"version-history":[{"count":2,"href":"https:\/\/temporaneo.arciserviziocivile.it\/ravenna\/wp-json\/wp\/v2\/pages\/26\/revisions"}],"predecessor-version":[{"id":228,"href":"https:\/\/temporaneo.arciserviziocivile.it\/ravenna\/wp-json\/wp\/v2\/pages\/26\/revisions\/228"}],"wp:attachment":[{"href":"https:\/\/temporaneo.arciserviziocivile.it\/ravenna\/wp-json\/wp\/v2\/media?parent=26"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}