{"id":319,"date":"2017-11-20T11:31:44","date_gmt":"2017-11-20T10:31:44","guid":{"rendered":"http:\/\/temporaneo.arciserviziocivile.it\/ascnetwork\/jesi\/?p=319"},"modified":"2017-11-23T10:10:01","modified_gmt":"2017-11-23T09:10:01","slug":"319","status":"publish","type":"post","link":"https:\/\/temporaneo.arciserviziocivile.it\/jesi\/2017\/11\/20\/319\/","title":{"rendered":"IL PERDONO garante della bellezza della vita"},"content":{"rendered":"<p>A dir poco emozionante e toccante il discorso di <strong>Daniel Lumera<\/strong> tenutosi durante la conferenza formativa del modulo &#8220;il valore della vita&#8221;, inerente al progetto &#8220;STORIE ALLA FINESTRA&#8221;, sabato 18 novembre scorso. I temi trattati erano: riscoprire il ruolo della morte all&#8217;interno della vita e l&#8217;esperienza della fondazione My Life Design presieduta dallo stesso Lumera sull&#8217;accompagnamento al morente attraverso la pratica laica del perdono.<\/p>\n<p><em>Vi siete mai interrogati su cosa sia il perdono? Quante volte avete perdonato e siete stati perdonati?\u00a0<\/em><!--more--><\/p>\n<p>&nbsp;<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-319 gallery-columns-3 gallery-size-medium'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/temporaneo.arciserviziocivile.it\/jesi\/2017\/11\/20\/319\/dsc_0758\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"201\" src=\"https:\/\/temporaneo.arciserviziocivile.it\/jesi\/wp-content\/uploads\/sites\/11\/DSC_0758-300x201.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/temporaneo.arciserviziocivile.it\/jesi\/wp-content\/uploads\/sites\/11\/DSC_0758-300x201.jpg 300w, https:\/\/temporaneo.arciserviziocivile.it\/jesi\/wp-content\/uploads\/sites\/11\/DSC_0758-768x514.jpg 768w, https:\/\/temporaneo.arciserviziocivile.it\/jesi\/wp-content\/uploads\/sites\/11\/DSC_0758-1024x685.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/temporaneo.arciserviziocivile.it\/jesi\/2017\/11\/20\/319\/dsc_0779-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"201\" src=\"https:\/\/temporaneo.arciserviziocivile.it\/jesi\/wp-content\/uploads\/sites\/11\/DSC_0779-1-300x201.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/temporaneo.arciserviziocivile.it\/jesi\/wp-content\/uploads\/sites\/11\/DSC_0779-1-300x201.jpg 300w, https:\/\/temporaneo.arciserviziocivile.it\/jesi\/wp-content\/uploads\/sites\/11\/DSC_0779-1-768x514.jpg 768w, https:\/\/temporaneo.arciserviziocivile.it\/jesi\/wp-content\/uploads\/sites\/11\/DSC_0779-1-1024x685.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/temporaneo.arciserviziocivile.it\/jesi\/2017\/11\/20\/319\/dsc_0774\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"201\" src=\"https:\/\/temporaneo.arciserviziocivile.it\/jesi\/wp-content\/uploads\/sites\/11\/DSC_0774-300x201.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/temporaneo.arciserviziocivile.it\/jesi\/wp-content\/uploads\/sites\/11\/DSC_0774-300x201.jpg 300w, https:\/\/temporaneo.arciserviziocivile.it\/jesi\/wp-content\/uploads\/sites\/11\/DSC_0774-768x514.jpg 768w, https:\/\/temporaneo.arciserviziocivile.it\/jesi\/wp-content\/uploads\/sites\/11\/DSC_0774-1024x685.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/temporaneo.arciserviziocivile.it\/jesi\/2017\/11\/20\/319\/dsc_0764\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"201\" src=\"https:\/\/temporaneo.arciserviziocivile.it\/jesi\/wp-content\/uploads\/sites\/11\/DSC_0764-300x201.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/temporaneo.arciserviziocivile.it\/jesi\/wp-content\/uploads\/sites\/11\/DSC_0764-300x201.jpg 300w, https:\/\/temporaneo.arciserviziocivile.it\/jesi\/wp-content\/uploads\/sites\/11\/DSC_0764-768x514.jpg 768w, https:\/\/temporaneo.arciserviziocivile.it\/jesi\/wp-content\/uploads\/sites\/11\/DSC_0764-1024x685.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/dt><\/dl>\n\t\t\t<br style='clear: both' \/>\n\t\t<\/div>\n\n<p>Il perdono non \u00e8 un azione, ma bens\u00ec un sentimento, un sentimento d\u2019amore e un atto di coraggio; Si sceglie di mantenersi in una condizione d\u2019amore, di liberarsi dall\u2019odio e dal rancore che ci esulano dalla nostra persona. Decidiamo di perdonare non per l\u2019altro, ma per noi stessi;<strong> ma per cosa&#8230; per essere felici? per ottenere la pace interiore? Forse&#8230;<\/strong> ma prima di tutto, per essere una persona libera, libera di scegliere chi poter essere. Sei solo tu, tu nel tuo universo, tu che riesci a metterti in contatto con te stesso, creando relazioni pi\u00f9 profonde con se stessi, solo cosi si riuscir\u00e0 ad accogliere ed amare la vita cosi com&#8217;\u00e8. Il perdono diventa appunto, secondo Lumera, un percorso che ci aiuta a ridefinire il senso della vita; un viaggio, forse il pi\u00f9 bello, attraverso noi stessi che ci permetter\u00e0 di <strong>sperimentare sentimenti di tranquillit\u00e0 e serenit\u00e0<\/strong>.<\/p>\n<p>Ricordate, perdonare non \u00e8 dimenticare&#8230;<\/p>\n<p>perdonare non vuol dire non reagire&#8230;<\/p>\n<p>il perdono non \u00e8 sinonimo di debolezza&#8230;<\/p>\n<p>il perdono ci permette di capire che l&#8217;odio non \u00e8 una strada che guarisce.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A dir poco emozionante e toccante il discorso di Daniel Lumera tenutosi durante la conferenza formativa del modulo &#8220;il valore della vita&#8221;, inerente al progetto &#8220;STORIE ALLA FINESTRA&#8221;, sabato 18&#8230;<\/p>\n","protected":false},"author":15,"featured_media":329,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"_links":{"self":[{"href":"https:\/\/temporaneo.arciserviziocivile.it\/jesi\/wp-json\/wp\/v2\/posts\/319"}],"collection":[{"href":"https:\/\/temporaneo.arciserviziocivile.it\/jesi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/temporaneo.arciserviziocivile.it\/jesi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/temporaneo.arciserviziocivile.it\/jesi\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/temporaneo.arciserviziocivile.it\/jesi\/wp-json\/wp\/v2\/comments?post=319"}],"version-history":[{"count":6,"href":"https:\/\/temporaneo.arciserviziocivile.it\/jesi\/wp-json\/wp\/v2\/posts\/319\/revisions"}],"predecessor-version":[{"id":334,"href":"https:\/\/temporaneo.arciserviziocivile.it\/jesi\/wp-json\/wp\/v2\/posts\/319\/revisions\/334"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/temporaneo.arciserviziocivile.it\/jesi\/wp-json\/wp\/v2\/media\/329"}],"wp:attachment":[{"href":"https:\/\/temporaneo.arciserviziocivile.it\/jesi\/wp-json\/wp\/v2\/media?parent=319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/temporaneo.arciserviziocivile.it\/jesi\/wp-json\/wp\/v2\/categories?post=319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/temporaneo.arciserviziocivile.it\/jesi\/wp-json\/wp\/v2\/tags?post=319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}